{"id":8478,"date":"2024-09-10T06:57:51","date_gmt":"2024-09-10T06:57:51","guid":{"rendered":"https:\/\/corpsdiplomaticnews.tg\/?p=8478"},"modified":"2024-09-10T09:07:47","modified_gmt":"2024-09-10T09:07:47","slug":"m-le-ministre-kokoroko-beaucoup-detablissements-de-la-capitale-manquent-de-tables-blancs-batiments-et-enseignants","status":"publish","type":"post","link":"https:\/\/corpsdiplomaticnews.tg\/index.php\/2024\/09\/10\/m-le-ministre-kokoroko-beaucoup-detablissements-de-la-capitale-manquent-de-tables-blancs-batiments-et-enseignants\/","title":{"rendered":"M. le  ministre Kokoroko, beaucoup d&rsquo;\u00e9tablissements de la capitale manquent de tables-blancs,   b\u00e2timents et enseignants"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La rentr\u00e9e des classes est fix\u00e9e au 16 septembre 2024 au Togo, mais beaucoup d\u2019\u00e9tablissements scolaires m\u00eame dans la capitale manquent de tout: tables-bancs, b\u00e2timents et surtout le personnel enseignant. \u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2023\/09\/KokorokoDisc-1024x768.jpg\" alt=\"\" class=\"wp-image-5813\" srcset=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2023\/09\/KokorokoDisc-1024x768.jpg 1024w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2023\/09\/KokorokoDisc-300x225.jpg 300w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2023\/09\/KokorokoDisc-768x576.jpg 768w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2023\/09\/KokorokoDisc-860x645.jpg 860w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2023\/09\/KokorokoDisc.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A moins d&rsquo;une semaine de la rentr\u00e9e, les \u00e9tablissements de Lom\u00e9 \u00e0 l&rsquo;instar  du Lyc\u00e9e Tokoin Est, Tokoin Centre, CEG WUITI  \u00e0 \u00eatre  dans un d\u00e9labrement total.  L&rsquo;ann\u00e9e derni\u00e8re, le manque de tables-bancs, de salles de classe et d&rsquo;enseignants ont  \u00e9t\u00e9 les grands probl\u00e8mes auxquels ces \u00e9tablissements ont fait face.  Cela a oblig\u00e9 certains \u00e9l\u00e8ves a commenc\u00e9 leur journ\u00e9e \u00e0 midi lorsque certains auront  pass\u00e9 dans la matin\u00e9e.  Une situation qui d\u00e9concentre la plupart des apprenants. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"1024\" src=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/08\/iford-721x1024.jpeg\" alt=\"\" class=\"wp-image-8318\" srcset=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/08\/iford-721x1024.jpeg 721w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/08\/iford-211x300.jpeg 211w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/08\/iford-768x1090.jpeg 768w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/08\/iford-1082x1536.jpeg 1082w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/08\/iford-860x1221.jpeg 860w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/08\/iford.jpeg 1127w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A une semaine de la rentr\u00e9e, beaucoup de parents  s&rsquo;interrogent si leurs enfants vont toujours \u00e9dudier dans les m\u00eames conditions cette ann\u00e9e 2024-2025. D&rsquo;o\u00f9 leur interpellation et inqui\u00e9tude vis-\u00e0-vis  du ministre Komla Dodzi KOKOROKO, de l&rsquo;enseignement primaire  et secondaire (<strong>photo<\/strong>). <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rentr\u00e9e des classes est fix\u00e9e au 16 septembre 2024 au Togo, mais beaucoup d\u2019\u00e9tablissements scolaires m\u00eame dans la capitale manquent de tout: tables-bancs, b\u00e2timents et surtout le personnel enseignant. \u00a0 A moins d&rsquo;une semaine de la rentr\u00e9e, les \u00e9tablissements de Lom\u00e9 \u00e0 l&rsquo;instar du Lyc\u00e9e Tokoin Est, Tokoin Centre, CEG WUITI \u00e0 \u00eatre dans [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,124],"tags":[],"class_list":["post-8478","post","type-post","status-publish","format-standard","has-post-thumbnail","category-education","category-la-une"],"_links":{"self":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts\/8478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/comments?post=8478"}],"version-history":[{"count":6,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts\/8478\/revisions"}],"predecessor-version":[{"id":8496,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts\/8478\/revisions\/8496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/media\/5813"}],"wp:attachment":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/media?parent=8478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/categories?post=8478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/tags?post=8478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}