{"id":7469,"date":"2024-03-02T12:18:55","date_gmt":"2024-03-02T12:18:55","guid":{"rendered":"https:\/\/corpsdiplomaticnews.tg\/?p=7469"},"modified":"2024-03-02T12:18:57","modified_gmt":"2024-03-02T12:18:57","slug":"loaci-et-lanac-tiennent-un-seminaire-sur-les-programmes-de-maintenance-et-de-fiabilite-des-aeronefs-a-lome","status":"publish","type":"post","link":"https:\/\/corpsdiplomaticnews.tg\/index.php\/2024\/03\/02\/loaci-et-lanac-tiennent-un-seminaire-sur-les-programmes-de-maintenance-et-de-fiabilite-des-aeronefs-a-lome\/","title":{"rendered":"L\u2019OACI et l\u2019ANAC tiennent un s\u00e9minaire sur les programmes de maintenance et de fiabilit\u00e9 des a\u00e9ronefs \u00e0 Lom\u00e9"},"content":{"rendered":"\n<p>L\u2019Organisation de l\u2019aviation civile internationale (OACI), en collaboration avec l\u2019Agence nationale de l\u2019aviation civile\u00a0 (ANAC-Togo), organise \u00a0du 26 f\u00e9vrier au 8 mars 2024 \u00a0\u00e0 Lom\u00e9, un s\u00e9minaire r\u00e9gional sur les programmes de maintenance et programmes de fiabilit\u00e9 des a\u00e9ronefs. Pendant deux semaines, les formateurs du g\u00e9ant de l\u2019a\u00e9ronautique Airbus vont renforcer\u00a0 les capacit\u00e9s des Inspecteurs des aviations civiles, des professionnels et exploitants a\u00e9riens venus de l\u2019Afrique occidentale, centrale et de Madagascar. Il s\u2019agit\u00a0 premi\u00e8rement de la mise en place des mesures pr\u00e9ventives obligatoires pour recommander des maintenances visant \u00e0 d\u00e9tecter et \u00e0 pr\u00e9venir les probl\u00e8mes potentiels avant qu\u2019ils ne deviennent sources de pr\u00e9occupations de s\u00e9curit\u00e9 des a\u00e9ronefs. Deuxi\u00e8mement, ils auront la capacit\u00e9 d\u2019anticipation des pannes, de r\u00e9duction au maximum des risques d\u2019accidents et \u00e0 s\u2019assurer de la disponibilit\u00e9 des a\u00e9ronefs dans les sous-r\u00e9gions susmentionn\u00e9es. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/DG-ANAC-1024x768.jpg\" alt=\"\" class=\"wp-image-7470\" srcset=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/DG-ANAC-1024x768.jpg 1024w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/DG-ANAC-300x225.jpg 300w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/DG-ANAC-768x576.jpg 768w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/DG-ANAC-860x645.jpg 860w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/DG-ANAC.jpg 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>                                                <strong>IDRISSOU Ahabou, Directeur G\u00e9n\u00e9ral de l&rsquo;ANAC-Togo<\/strong><\/p>\n\n\n\n<p>\u00ab <em>L\u2019objet de ce s\u00e9minaire est de s\u2019assurer que les programmes de maintenance et les programmes de fiabilit\u00e9 pour les a\u00e9ronefs soient effectu\u00e9s<\/em> \u00bb, a expliqu\u00e9 Monsieur IDRISSOU Ahabou, Directeur g\u00e9n\u00e9ral de l\u2019ANAC-Togo, soulignant que le souci de cette rencontre est de garantir la s\u00e9curit\u00e9 et la fiabilit\u00e9 des op\u00e9rations a\u00e9riennes dans ces r\u00e9gions et dans le monde.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/ANAC-2-1024x768.jpg\" alt=\"\" class=\"wp-image-7471\" srcset=\"https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/ANAC-2-1024x768.jpg 1024w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/ANAC-2-300x225.jpg 300w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/ANAC-2-768x576.jpg 768w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/ANAC-2-860x645.jpg 860w, https:\/\/corpsdiplomaticnews.tg\/wp-content\/uploads\/2024\/03\/ANAC-2.jpg 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00a0                                                       <strong>PHOTO DE FAMILLE DES PARTICIPANTS <\/strong><\/p>\n\n\n\n<p>\u00ab\u00a0<em>Ces programmes se situent dans le cadre des activit\u00e9s d\u2019Airbus visant exclusivement \u00e0 l\u2019am\u00e9lioration de la s\u00e9curit\u00e9 du transport a\u00e9rien. Airbus est\u00a0 un \u00a0fabriquant d\u2019avions, tout le monde le sait.\u00a0 Nous fabriquons de bons avions, ce que les gens savent moins, c\u2019est que nous avons un d\u00e9partement pour l\u2019am\u00e9lioration de la s\u00e9curit\u00e9 du transport a\u00e9rien\u00a0pas seulement en interne Airbus. Il y a des \u00e9quipes qui travaillent sur ces aspects pendant toute la vie de nos produit<\/em>s\u00bb, a d\u00e9clar\u00e9 Maurry Seck, formateur Airbus.<\/p>\n\n\n\n<p>Les travaux sont en cours et poursuivent jusqu\u2019au 8 mars prochain dans la capitale togolaise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Organisation de l\u2019aviation civile internationale (OACI), en collaboration avec l\u2019Agence nationale de l\u2019aviation civile\u00a0 (ANAC-Togo), organise \u00a0du 26 f\u00e9vrier au 8 mars 2024 \u00a0\u00e0 Lom\u00e9, un s\u00e9minaire r\u00e9gional sur les programmes de maintenance et programmes de fiabilit\u00e9 des a\u00e9ronefs. Pendant deux semaines, les formateurs du g\u00e9ant de l\u2019a\u00e9ronautique Airbus vont renforcer\u00a0 les capacit\u00e9s des Inspecteurs [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,124],"tags":[],"class_list":{"0":"post-7469","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-azimuts","8":"category-la-une"},"_links":{"self":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts\/7469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/comments?post=7469"}],"version-history":[{"count":1,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts\/7469\/revisions"}],"predecessor-version":[{"id":7472,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/posts\/7469\/revisions\/7472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/media\/7470"}],"wp:attachment":[{"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/media?parent=7469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/categories?post=7469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corpsdiplomaticnews.tg\/index.php\/wp-json\/wp\/v2\/tags?post=7469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}